{"id":326561,"date":"2026-05-13T10:30:25","date_gmt":"2026-05-13T08:30:25","guid":{"rendered":"https:\/\/www.padelfip.com\/?p=326561"},"modified":"2026-05-13T14:39:29","modified_gmt":"2026-05-13T12:39:29","slug":"bratislava-celebra-el-debut-del-cupra-fip-tour-en-eslovaquia","status":"publish","type":"post","link":"https:\/\/www.padelfip.com\/es\/2026\/05\/bratislava-celebra-el-debut-del-cupra-fip-tour-en-eslovaquia\/","title":{"rendered":"Bratislava celebra el debut del CUPRA FIP Tour en Eslovaquia"},"content":{"rendered":"<p>Este ser\u00e1 un fin de semana importante para el p\u00e1del internacional, ya que marcar\u00e1 un nuevo paso en su expansi\u00f3n global con el debut del <strong>CUPRA FIP Tour<\/strong> en <strong>Eslovaquia<\/strong>, donde se disputar\u00e1 el <strong>FIP Bronze<\/strong> de <strong>Bratislava<\/strong>. Este pa\u00eds es uno de los 17 nuevos Estados que este a\u00f1o ya han acogido o acoger\u00e1n una prueba del circuito. Seg\u00fan los datos del World Padel Report 2025 de la Federaci\u00f3n Internacional de P\u00e1del, en Eslovaquia hay 10.000 jugadores amateur.<\/p>\n<p>&nbsp;<\/p>\n<p>En Bratislava, <strong>Adri Nar\u00e1njo<\/strong> y <strong>Pablo S\u00e1nchez<\/strong> podr\u00edan estar en disposici\u00f3n de lograr su tercer t\u00edtulo de la temporada. Estos dos jugadores son los cabezas de serie n\u00famero 1 del torneo y en 2026 ya han triunfado en los FIP Bronze de Nairobi (Kenia) y Singapur. Entre sus principales rivales se encuentran <strong>Simone Iacovino<\/strong> y <strong>Giulio Graziotti<\/strong>, finalistas en el FIP Bronze Hong Kong II a finales de marzo. Tambi\u00e9n entre los aspirantes al t\u00edtulo est\u00e1n la pareja italiana formada por <strong>Federico Galli-Lorenzo Di Giovanni<\/strong> y <strong>Thomas Vanbauce-Julien Seurin<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>En el cuadro femenino, hay una pareja en busca de su cuarto t\u00edtulo del a\u00f1o: <strong>Claudia Escacena<\/strong> y <strong>M\u00f3nica G\u00f3mez Rivas<\/strong>. Las dos jugadoras espa\u00f1olas triunfaron en marzo en los FIP Bronze de Helsingborg (Suecia), Houten (Pa\u00edses Bajos) y Viseu (Portugal). Sus principales rivales por el t\u00edtulo son <strong>Xenia Clasca Vidiella<\/strong> y <strong>Lorena Vano<\/strong>. En Bratislava estar\u00e1n tambi\u00e9n las jugadoras italianas Emily Stellato, reciente finalista del FIP Silver de Teramo junto a <strong>Carolina Orsi<\/strong>, <strong>y Giulia Sussarello<\/strong>. Tambi\u00e9n habr\u00e1 que seguir de cerca a <strong>Sara Foguer Lapuente<\/strong> y <strong>Eugenia Guimet<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este ser\u00e1 un fin de semana importante para el p\u00e1del internacional, ya que marcar\u00e1 un nuevo paso en su expansi\u00f3n global con el debut del CUPRA FIP Tour en Eslovaquia, donde se disputar\u00e1 el FIP Bronze de Bratislava. Este pa\u00eds es uno de los 17 nuevos Estados que este a\u00f1o ya han acogido o acoger\u00e1n [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":326565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[548],"tags":[],"class_list":["post-326561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fip-bronze-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/posts\/326561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/comments?post=326561"}],"version-history":[{"count":2,"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/posts\/326561\/revisions"}],"predecessor-version":[{"id":326563,"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/posts\/326561\/revisions\/326563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/media\/326565"}],"wp:attachment":[{"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/media?parent=326561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/categories?post=326561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.padelfip.com\/es\/wp-json\/wp\/v2\/tags?post=326561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}